{"id":554888,"date":"2014-09-09T10:01:10","date_gmt":"2014-09-09T13:01:10","guid":{"rendered":"https:\/\/2014.riodejaneiro.wordcamp.org\/?p=554888"},"modified":"2014-09-09T10:02:37","modified_gmt":"2014-09-09T13:02:37","slug":"desconstruindo-o-layout-do-wordcamprj","status":"publish","type":"post","link":"https:\/\/riodejaneiro.wordcamp.org\/2014\/noticias\/desconstruindo-o-layout-do-wordcamprj\/","title":{"rendered":"Desconstruindo o layout do WordCampRJ"},"content":{"rendered":"<h3>Agora que o site est\u00e1 completo, bora desconstru\u00ed-lo! \ud83d\ude00<\/h3>\n<p>Brincadeira, vou contar pra voc\u00eas um pouco de como foi o meu processo de estudo, concep\u00e7\u00e3o e cria\u00e7\u00e3o do layout do site WordCampRJ, que foi codificado pelo Gustavo Bordoni, um dos organizadores do evento.<\/p>\n<p>Muito antes de pensar em HTML e CSS os amigos da organiza\u00e7\u00e3o me pediram para criar o PPT da apresenta\u00e7\u00e3o da proposta de loca\u00e7\u00e3o no come\u00e7o desse ano. Ainda n\u00e3o t\u00ednhamos conversado com o Senac na \u00e9poca e est\u00e1vamos prospectando pela cidade e esse PPT foi a porta de entrada para o layout.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/2014.riodejaneiro.wordcamp.org\/files\/2014\/09\/thumb-apresentacao-ppt-para-locacao.jpg?resize=700%2C270&#038;ssl=1\" alt=\"thumb-apresentacao-ppt-para-locacao\" width=\"700\" height=\"270\" class=\"aligncenter size-full wp-image-555030\" srcset=\"https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-apresentacao-ppt-para-locacao.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-apresentacao-ppt-para-locacao.jpg?resize=300%2C115&amp;ssl=1 300w, https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-apresentacao-ppt-para-locacao.jpg?resize=500%2C192&amp;ssl=1 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Por causa dele eu fiz uma pesquisa bem profunda nos sites das outras cidades l\u00e1 na Central WordCamp dos \u00faltimos 2 anos, e que me gerou um &#8220;<a href=\"https:\/\/docs.google.com\/document\/d\/1Jz-CtwpHpmM0hPMzd5vlydZboyhgEr2J9pCUYFVTZDQ\/pub\" title=\"Projeto visual WordCamp RJ 2014 - Esse link abre numa nova janela\" target=\"_blank\">DOC XICANTE<\/a>&#8220;, e dele a estrutura de p\u00e1ginas para o projeto.<\/p>\n<h3>Integrando os conceitos com o Front\/Back-end antes de abrir o Photoshop<\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/2014.riodejaneiro.wordcamp.org\/files\/2014\/09\/thumb-features-admin-wordcamp-site.jpg?resize=165%2C214&#038;ssl=1\" alt=\"&#039;Custom post Type&#039; e &#039;Custom post Taxonomy&#039; padr\u00f5es dos sites WordCamp\" width=\"165\" height=\"214\" class=\"alignleft size-full wp-image-555058\" \/>O site do WordCamp obedece um formato pr\u00f3prio, todo pensado no modelo do evento. No tema disponibilizado para as cidades pelo WordPress, n\u00f3s n\u00e3o podemos mexer no XHTML, ficando \u00e0 cargo do CSS toda a estiliza\u00e7\u00e3o do tema. <\/p>\n<p>Mas a\u00ed voc\u00ea diria: &#8220;<em><strong>u\u00e9, n\u00e3o \u00e9 esse o conceito dos padr\u00f5es web, igual como faz\u00edamos no saudoso CSS Zen Garden?<\/strong><\/em>&#8221; Sim, \u00e9. Mas ainda sim, limitar o XHTML e se diferenciar dos demais WordCamps era o grande desafio, e n\u00e3o &#8220;layoutar&#8221; pelo CSS. Mesmo porque, o Bordoni \u00e9 um verdadeiro Neymar como front\/back-end, e isso n\u00e3o foi um problema pra ele! \ud83d\ude00<\/p>\n<p>Depois de conversar um bocado com ele sobre as &#8216;<em>Custom post Types<\/em>&#8216; e &#8216;<em>Custom post Taxonomy<\/em>&#8216; do tema (&#8216;<em>Speakers<\/em>&#8216;, &#8216;<em>Sponsors<\/em>&#8216;, &#8216;<em>Organizers<\/em>&#8216;, etc.), eu parti para a cria\u00e7\u00e3o das duas telas de &#8216;<em>wireframes<\/em>&#8216; conceituais, que uma vez aprovadas pelos amigos da organiza\u00e7\u00e3o, eu finalizei as p\u00e1ginas restantes e ent\u00e3o comecei a desenhar o layout em PSD.<\/p>\n<h3>Hora de digitar &#8220;CTRL + N&#8221; no Photoshop<\/h3>\n<p>O apelo mais forte do layout \u00e9 a identifica\u00e7\u00e3o da cidades pelos seus cart\u00f5es-postais. Ok, \u00e9 um pouco clich\u00ea sim, mas como o evento \u00e9 internacional, fugir desse conceito seria um tiro no p\u00e9, basta ver o resultado da pesquisa que eu fiz nos outros sites. <\/p>\n<p>O principal diferencial seria mostrar nitidamente as caracter\u00edsticas da cidade no layout em si. E coube \u00e0s imagens dos principais pontos tur\u00edsticos esse papel. Esse conceito ficou t\u00e3o emblem\u00e1tico para n\u00f3s, que o utilizamos inclusive nas cotas de patroc\u00ednios que receberam nomes com esse tema. Para cada p\u00e1gina, uma imagem aleat\u00f3ria de um foto do Rio de Janeiro seria exibida no &#8216;<em>background<\/em>&#8216;, com exce\u00e7\u00e3o da &#8220;Home&#8221; que tem a imagem fixa da est\u00e1tua do mestre <strong>Carlos Drummond de Andrade<\/strong>. <\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/2014.riodejaneiro.wordcamp.org\/files\/2014\/09\/thumb-estatua-drummond-de-andrade-em-copacabana.jpg?resize=700%2C270&#038;ssl=1\" alt=\"thumb-estatua-drummond-de-andrade-em-copacabana\" width=\"700\" height=\"270\" class=\"aligncenter size-full wp-image-555039\" srcset=\"https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-estatua-drummond-de-andrade-em-copacabana.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-estatua-drummond-de-andrade-em-copacabana.jpg?resize=300%2C115&amp;ssl=1 300w, https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-estatua-drummond-de-andrade-em-copacabana.jpg?resize=500%2C192&amp;ssl=1 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Dentre as fotos n\u00f3s escolhemos a <strong>praia de Copacabana<\/strong>, o <strong>P\u00e3o de A\u00e7\u00facar<\/strong>, <strong>Corcovado<\/strong>, <strong>Maracan\u00e3<\/strong> e os <strong>Arcos da Lapa<\/strong> como atra\u00e7\u00f5es visuais para o site.<\/p>\n<p>Um tema bastante discutido entre a galera da organiza\u00e7\u00e3o foi a paleta de cores do projeto. O bicho pegou nos bastidores, e a discuss\u00e3o ficou entre os argumentos &#8220;<em><strong>as cores est\u00e3o muito americanizadas<\/strong><\/em>&#8221; e &#8220;<em><strong>quais s\u00e3o as verdadeiras cores que representam o Rio de janeiro?<\/strong><\/em>&#8221; e como n\u00e3o chegamos a um consenso eu bati o martelo e optei pelas <a href=\"https:\/\/wordpress.org\/about\/logos\/\" title=\"WordPress &quot;Logos and Graphics&quot; | Esse link abre numa nova janela\" target=\"_blank\">cores oficial do WordPress<\/a> porque entendi que elas n\u00e3o ferem a identidade carioca do site.<\/p>\n<p>Como n\u00f3s usamos o tema &#8216;Twenty Thirteen&#8217; como base para editar o CSS, obedecemos tanto a sua tipologia nativa, como tamb\u00e9m o seu pequeno grupo de \u00edcones nas postagens.<\/p>\n<h3>Desconstruindo o layout<\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/2014.riodejaneiro.wordcamp.org\/files\/2014\/09\/thumb-layout-pagina-programacao.jpg?resize=350%2C467&#038;ssl=1\" alt=\"Layout da p\u00e1gina &quot;Programa\u00e7\u00e3o&quot;\" width=\"350\" height=\"467\" class=\"alignright size-full wp-image-555042\" srcset=\"https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-layout-pagina-programacao.jpg?w=350&amp;ssl=1 350w, https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/thumb-layout-pagina-programacao.jpg?resize=224%2C300&amp;ssl=1 224w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Na p\u00e1gina &#8220;Programa\u00e7\u00e3o&#8221; criamos uma legenda baseadas em cores para diferenciar os tipos de palestras, facilitando o entendimento dos usu\u00e1rios dos conte\u00fados apresentados. Na tabela, todos os palestrantes possuem links \u00e2ncora apontado para a sua posi\u00e7\u00e3o na p\u00e1gina &#8220;Palestrantes&#8221;, que mesmo sendo de exibi\u00e7\u00e3o aleat\u00f3ria, aportam no avatar e descri\u00e7\u00e3o do palestrante desejado.<\/p>\n<p>J\u00e1 na p\u00e1gina &#8220;Patrocinadores&#8221;, criamos uma estrutura de visualiza\u00e7\u00e3o do respectivo logotipo baseado na cota contratada. Ou seja, quanto maior a cota, maior o tamanho exibido do logotipo na tela. Al\u00e9m disso, contemplamos nessa p\u00e1gina a listagem de &#8220;Patrocinadores Lapa&#8221;, que \u00e9 uma forma de micro-patroc\u00ednio feito por uma pessoa f\u00edsica, como forma de apoiar o evento, que, em contrapartida, tem o seu link divulgado nessa p\u00e1gina tamb\u00e9m, claro!<\/p>\n<p>Outro destaque \u00e9 a p\u00e1gina que preparamos chamada &#8220;Guia de Sobreviv\u00eancia&#8221; para orientar o usu\u00e1rio que vai ao evento e mora num bairro mais distante, cidade, ou at\u00e9 mesmo em outro pa\u00eds e n\u00e3o conhece nada no entorno do Senac e precisa de um apoio em refer\u00eancias da organiza\u00e7\u00e3o. Essa p\u00e1gina \u00e9 um \u00edndice para as sub-p\u00e1ginas &#8220;Como chegar&#8221;, com orienta\u00e7\u00f5es das principais portas de entradas da cidade; &#8220;Onde se hospedar&#8221; com um mapa dos principais hot\u00e9is via Google Maps e &#8220;Onde almo\u00e7ar&#8221; com uma enorme lista das principais op\u00e7\u00f5es para fazer uma refei\u00e7\u00e3o.<\/p>\n<h3>Um projeto que cabe no seu smartphone<\/h3>\n<p>E claro, n\u00e3o pod\u00edamos deixar esse tema de fora, todo esse projeto \u00e9 &#8216;web responsivo&#8217;, ou seja, roda bonito nos dispositivos m\u00f3veis, mas se voc\u00ea ainda n\u00e3o sabe nada sobre esse assunto, se inscreva no evento que vamos falar sobre isso tamb\u00e9m no meu painel! \ud83d\ude00<\/p>\n<p>Esperamos que voc\u00eas tenham gostado do site e nos vemos no dia 20 de setembro!<br \/>\nAt\u00e9 la!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agora que o site est\u00e1 completo, bora desconstru\u00ed-lo! \ud83d\ude00 Brincadeira, vou contar pra voc\u00eas um pouco de como foi o meu processo de estudo, concep\u00e7\u00e3o e cria\u00e7\u00e3o do layout do site WordCampRJ, que foi codificado pelo Gustavo Bordoni, um dos organizadores do evento. Muito antes de pensar em HTML e CSS os amigos da organiza\u00e7\u00e3o &hellip; <a href=\"https:\/\/riodejaneiro.wordcamp.org\/2014\/noticias\/desconstruindo-o-layout-do-wordcamprj\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">Desconstruindo o layout do WordCampRJ<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":149599,"featured_media":555057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[324],"tags":[20598,364802,364367,364555,364920,364049],"class_list":["post-554888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-layout","tag-paletas-de-cores","tag-photoshop","tag-psd","tag-tipologia","tag-wireframe"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/riodejaneiro.wordcamp.org\/2014\/files\/2014\/09\/imagem-destacada-desconstruindo-o-layout-do-wordcamprj.jpg?fit=700%2C270&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/554888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/users\/149599"}],"replies":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/comments?post=554888"}],"version-history":[{"count":31,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/554888\/revisions"}],"predecessor-version":[{"id":555059,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/554888\/revisions\/555059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/media\/555057"}],"wp:attachment":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=554888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/categories?post=554888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2014\/wp-json\/wp\/v2\/tags?post=554888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}