{"id":558377,"date":"2016-09-24T16:45:20","date_gmt":"2016-09-24T19:45:20","guid":{"rendered":"http:\/\/2016.riodejaneiro.wordcamp.org\/?p=558377"},"modified":"2016-09-24T16:49:14","modified_gmt":"2016-09-24T19:49:14","slug":"convocacao-wordcana","status":"publish","type":"post","link":"https:\/\/riodejaneiro.wordcamp.org\/2016\/convocacao-wordcana\/","title":{"rendered":"Convoca\u00e7\u00e3o WordCana"},"content":{"rendered":"<p>Nada melhor do que relaxar batendo um papo informal com a galera e tomando aquela cerva ou refri ap\u00f3s\u00a0um dia de aprendizado intenso, certo?<\/p>\n<p>Pensando nisso, orgulhosamente convocamos todos os WordCampers para o <strong>WordCana Rio de Janeiro 2016<\/strong>!<!--more--><\/p>\n<p>Essa edi\u00e7\u00e3o ser\u00e1 realizada ao estilo bem carioca, a partir das <strong>18h<\/strong>\u00a0no Bar\u00a0<strong>Adega Villas Boas Tijuca<\/strong>, que fica localizado na <strong>Rua Santa Lu\u00edza, 486 &#8211; Tijuca<\/strong>,\u00a0proximidades da Pra\u00e7a Vanhargem, regi\u00e3o mais conhecida como Buxixo. Apenas a 2Km (<a href=\"https:\/\/www.google.com.br\/maps\/dir\/Universidade+Veiga+de+Almeida,+Tijuca+-+Rua+Ibituruna+-+Maracan\u00e3,+Rio+de+Janeiro+-+RJ\/Adega+Villas+Boas+Tijuca+-+Rua+Santa+Lu\u00edza,+486+-+Tijuca,+Rio+de+Janeiro+-+RJ,+20511-030\/@-22.9155886,-43.2330997,16z\/data=!3m1!4b1!4m13!4m12!1m5!1m1!1s0x997e57963eedf3:0xaf52199fd71ffebb!2m2!1d-43.2214567!2d-22.9119034!1m5!1m1!1s0x9be00c5fd3acd9:0x7b6d19a680d2da11!2m2!1d-43.2359879!2d-22.9182499\" target=\"_blank\">Rota<\/a>) do local do evento e a 1Km de esta\u00e7\u00e3o de Metro Saes Pe\u00f1a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-558429\" src=\"http:\/\/2016.riodejaneiro.wordcamp.org\/files\/2016\/09\/convocacao-wordcana.jpg\" alt=\"convocacao-wordcana\" width=\"600\" height=\"340\" srcset=\"https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/convocacao-wordcana.jpg 600w, https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/convocacao-wordcana-300x170.jpg 300w, https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/convocacao-wordcana-500x283.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><!--more-->Al\u00e9m do seu bem estar, estamos preocupados tamb\u00e9m com seu bolso. \u00a0Por isso, o local escolhido conta com pre\u00e7o justo e trabalha com comandas\u00a0<strong>individuais<\/strong>, evitando aquela confus\u00e3o na hora de\u00a0fechar a conta. O bar ainda conta com\u00a0card\u00e1pio variado de bebidas e pratos com carnes, peixes, petiscos e pizzas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-558430\" src=\"http:\/\/2016.riodejaneiro.wordcamp.org\/files\/2016\/09\/13161762_1098120523594918_4111452151662435619_o.jpg\" alt=\"13161762_1098120523594918_4111452151662435619_o\" width=\"2048\" height=\"1157\" srcset=\"https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/13161762_1098120523594918_4111452151662435619_o.jpg 2048w, https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/13161762_1098120523594918_4111452151662435619_o-300x169.jpg 300w, https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/13161762_1098120523594918_4111452151662435619_o-768x434.jpg 768w, https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/13161762_1098120523594918_4111452151662435619_o-1024x579.jpg 1024w, https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/13161762_1098120523594918_4111452151662435619_o-500x282.jpg 500w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p>Essa \u00e9 uma \u00f3tima oportunidade pra conhecer melhor a galera comunidade ou trocar uma ideia com um dos palestrantes. <strong>Esperamos todos l\u00e1<\/strong>!<\/p>\n<p><a class=\"wcrj-btn\" href=\"https:\/\/2016.riodejaneiro.wordcamp.org\/guia-de-sobrevivencia\/\" target=\"_blank\">Acesse o Guia de Sobreviv\u00eancia e organize-se!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nada melhor do que relaxar batendo um papo informal com a galera e tomando aquela cerva ou refri ap\u00f3s\u00a0um dia de aprendizado intenso, certo? Pensando nisso, orgulhosamente convocamos todos os WordCampers para o WordCana Rio de Janeiro 2016!<\/p>\n","protected":false},"author":5964605,"featured_media":558447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[191223],"tags":[],"class_list":["post-558377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/riodejaneiro.wordcamp.org\/2016\/files\/2016\/09\/imagem-destacada-convocacao-wordcana.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheQz2-2lg5","_links":{"self":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/558377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/5964605"}],"replies":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=558377"}],"version-history":[{"count":11,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/558377\/revisions"}],"predecessor-version":[{"id":558844,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/558377\/revisions\/558844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/558447"}],"wp:attachment":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=558377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=558377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=558377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}