{"id":2453,"date":"2024-07-25T16:09:57","date_gmt":"2024-07-25T19:09:57","guid":{"rendered":"https:\/\/riodejaneiro.wordcamp.org\/2024\/?post_type=wcb_session&#038;p=2453"},"modified":"2024-08-29T08:45:22","modified_gmt":"2024-08-29T11:45:22","slug":"internacionalizacao-de-carreira-e-empresa","status":"publish","type":"wcb_session","link":"https:\/\/riodejaneiro.wordcamp.org\/2024\/session\/internacionalizacao-de-carreira-e-empresa\/","title":{"rendered":"Internacionaliza\u00e7\u00e3o de Carreira e Empresa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nesta palestra inspiradora e informativa, Pieter van Wyk, um renomado profissional com vasta experi\u00eancia em tecnologia e neg\u00f3cios, revelar\u00e1 os segredos da comunica\u00e7\u00e3o eficaz na internacionaliza\u00e7\u00e3o de carreiras e empresas. Com uma trajet\u00f3ria profissional diversificada e sucesso no mercado global, Pieter compartilhar\u00e1 insights valiosos sobre como desenvolver habilidades de comunica\u00e7\u00e3o que s\u00e3o essenciais para navegar pelos desafios e aproveitar as oportunidades do cen\u00e1rio internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Descubra como a comunica\u00e7\u00e3o eficaz pode ser uma poderosa alavanca para o crescimento pessoal e empresarial, permitindo explorar novos mercados, cultivar uma rede de contatos internacional e posicionar sua marca no palco mundial. Aprenda sobre as nuances culturais e lingu\u00edsticas que impactam a comunica\u00e7\u00e3o entre empresas internacionais, multinacionais e transnacionais, e como cada uma opera no contexto global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pieter tamb\u00e9m abordar\u00e1 as tend\u00eancias atuais, como o nomadismo digital, e como a tecnologia est\u00e1 transformando a forma como nos comunicamos al\u00e9m das fronteiras tradicionais. Entenda os principais objetivos e motiva\u00e7\u00f5es por tr\u00e1s da internacionaliza\u00e7\u00e3o, e como preparar sua empresa e carreira para se comunicar com sucesso no cen\u00e1rio global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o perca esta oportunidade de adquirir conhecimentos valiosos e se inspirar a aprimorar suas habilidades de comunica\u00e7\u00e3o para expandir seus horizontes profissionais e empresariais. Junte-se a n\u00f3s para explorar o vasto mundo das oportunidades globais com Pieter van Wyk e dominar a arte da comunica\u00e7\u00e3o internacional.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/28IHP-Wj4oE?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=pt-BR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nesta palestra inspiradora e informativa, Pieter van Wyk, um renomado profissional com vasta experi\u00eancia em tecnologia e neg\u00f3cios, revelar\u00e1 os segredos da comunica\u00e7\u00e3o eficaz na internacionaliza\u00e7\u00e3o de carreiras e empresas. Com uma trajet\u00f3ria profissional diversificada e sucesso no mercado global, Pieter compartilhar\u00e1 insights valiosos sobre como desenvolver habilidades de comunica\u00e7\u00e3o que s\u00e3o essenciais para navegar [&hellip;]<\/p>\n","protected":false},"author":1773513,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1723906200,"_wcpt_session_duration":2400,"_wcpt_session_type":"session","_wcpt_session_slides":"https:\/\/riodejaneiro.wordcamp.org\/2024\/files\/2024\/08\/pieter-van-wyk-internacionalizacao-carreira-empresa.pdf","_wcpt_session_video":"","_wcpt_speaker_id":[2446],"footnotes":""},"session_track":[53],"session_category":[49],"class_list":["post-2453","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-cinema","wcb_session_category-desenvolvimento"],"jetpack_sharing_enabled":true,"session_date_time":{"date":"17\/08\/2024","time":"11:50"},"session_speakers":[{"id":"2446","slug":"pieter-van-wik","name":"Pieter Van Wik","link":"https:\/\/riodejaneiro.wordcamp.org\/2024\/speaker\/pieter-van-wik\/"}],"session_cats_rendered":"Desenvolvimento","_links":{"self":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/sessions\/2453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":5,"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/sessions\/2453\/revisions"}],"predecessor-version":[{"id":3292,"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/sessions\/2453\/revisions\/3292"}],"speakers":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/speakers\/2446"}],"author":[{"embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wporg\/v1\/users\/leobaiano"}],"wp:attachment":[{"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/media?parent=2453"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/session_track?post=2453"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/riodejaneiro.wordcamp.org\/2024\/wp-json\/wp\/v2\/session_category?post=2453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}